{"id":1441,"date":"2016-02-22T16:17:41","date_gmt":"2016-02-22T16:17:41","guid":{"rendered":"https:\/\/sosgarde.ca\/blogue\/?p=1441"},"modified":"2023-04-13T21:01:18","modified_gmt":"2023-04-13T21:01:18","slug":"rester-proche-quand-vous-etes-au-loin","status":"publish","type":"post","link":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin","title":{"rendered":"Rester proche quand vous \u00eates au loin"},"content":{"rendered":"<span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\">2<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p><span style=\"font-weight: 400;\">Heureusement, je ne voyage plus autant pour le travail que je ne le faisais mais il y avait un temps o\u00f9 je prenais trois ou quatre vols par semaine. J\u2019avais l&#8217;habitude de dire que, pour moi, prendre un avion \u00e9tait comme prendre un bus. Voyager peut \u00eatre excitant, mais quand vous avez des enfants, cela peut aussi \u00eatre difficile. Voici quelques-uns de nos conseils pratiques pour savoir comment rester proche quand vous \u00eates au loin:<\/span><\/p>\n<p><b><a href=\"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2016\/02\/Untitled-design1.png\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-1442\" src=\"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2016\/02\/Untitled-design1-300x300.png\" alt=\"enfant ordinateur skype\" width=\"300\" height=\"300\" srcset=\"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2016\/02\/Untitled-design1-300x300.png 300w, https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2016\/02\/Untitled-design1-150x150.png 150w, https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2016\/02\/Untitled-design1.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><em>Avant de partir<\/em><\/b><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> Assurez-vous de pr\u00e9venir vos enfants de vos plans \u00e0 l&#8217;avance pour \u00e9viter les surprises.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Expliquez combien de temps vous serez au loin, par exemple, deux nuits, et que vous serez de retour.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Donnez un parfum excitant \u00e0 la nouvelle en regardant votre destination sur une carte ou en ligne.<\/span><\/li>\n<\/ul>\n<p><b><em>Lorsque vous \u00eates au loin<\/em> <\/b><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> Pr\u00e9voyez un appel ou un Skype tous les jours, \u00e0 la m\u00eame heure. Trouvez le moment qui fonctionne le mieux: pour commencer la journ\u00e9e, avant d\u2019aller \u00e0 l&#8217;\u00e9cole ou chaque soir avant le coucher.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Envoyez-vous mutuellement des selfies. Pas besoin d&#8217;\u00e9clairage sp\u00e9cial ou d\u2019un maquillage complet. Il suffit de prendre quelques photos amusantes de vous-m\u00eame au long de votre journ\u00e9e et de les envoyer avec un petit mot.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Cr\u00e9ez des traditions ludiques telles qu\u2019envoyer une carte postale de chaque ville que vous visitez qui peut aller sur un panneau dans les chambres de vos enfants. Pour faciliter les choses, gardez une r\u00e9serve de timbres dans votre valise, choisissez la carte postale avant de r\u00e9cup\u00e9rer vos bagages \u00e0 l&#8217;a\u00e9roport et \u00e9crivez-la pendant le trajet final vers votre destination.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> Nous recommandons d\u2019\u00e9viter de ramener un cadeau de chaque voyage car cela peut vite devenir une pratique co\u00fbteuse!<\/span><\/li>\n<\/ul>\n<p><em><b>Quand vous revenez<\/b><\/em><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> Pr\u00e9voyez quelque chose de sp\u00e9cial ou d\u2019amusant pour f\u00eater votre retour. Il ne s\u2019agit pas de d\u00e9penser de l&#8217;argent pour soulager une certaine culpabilit\u00e9 mais de passer du temps de qualit\u00e9 ensemble.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\"><em>Bon voyage maman ou papa!<\/em> <\/span><\/p>\n<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/sosgarde.ca\/blogue\/envie-de-moments-reserves-aux-grands-en-vacances\/\">Envie de moments \u00ab r\u00e9serv\u00e9s aux grands\u00bb en vacances?<\/a><\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">SOSgarde.ca est un portail canadien con\u00e7u pour vous aider \u00e0 trouver de l\u2019aide \u00e0 domicile pr\u00e8s de chez vous, facilement et rapidement. <\/span><\/i><a href=\"https:\/\/sosgarde.ca\/\"><i><span style=\"font-weight: 400;\">L&#8217;aide dont votre famille a besoin est \u00e0 port\u00e9e de souris!<\/span><\/i><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\">2<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span> Heureusement, je ne voyage plus autant pour le travail que je ne le faisais mais il y avait un temps o\u00f9 je prenais trois ou quatre vols par semaine. J\u2019avais l&#8217;habitude de dire que, pour moi, prendre un avion \u00e9tait comme prendre un bus. Voyager peut \u00eatre excitant, mais quand vous avez des enfants, cela [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[547],"tags":[39,19,379,21,378,377],"class_list":["post-1441","post","type-post","status-publish","format-standard","hentry","category-nanny","tag-conseils","tag-gardienne","tag-loin","tag-nounou","tag-proche","tag-voyage-sans-enfants"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rester proche quand vous \u00eates au loin - SOSgarde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rester proche quand vous \u00eates au loin - SOSgarde\" \/>\n<meta property=\"og:description\" content=\"Reading Time: 2 minutes Heureusement, je ne voyage plus autant pour le travail que je ne le faisais mais il y avait un temps o\u00f9 je prenais trois ou quatre vols par semaine. J\u2019avais l&#8217;habitude de dire que, pour moi, prendre un avion \u00e9tait comme prendre un bus. Voyager peut \u00eatre excitant, mais quand vous avez des enfants, cela [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin\" \/>\n<meta property=\"og:site_name\" content=\"SOSgarde\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-22T16:17:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-13T21:01:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2016\/02\/Untitled-design1-300x300.png\" \/>\n<meta name=\"author\" content=\"Sosgarde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sosgarde\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/rester-proche-quand-vous-etes-au-loin#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/rester-proche-quand-vous-etes-au-loin\"},\"author\":{\"name\":\"Sosgarde\",\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#\\\/schema\\\/person\\\/049d0f324600c83487a66abc831867fc\"},\"headline\":\"Rester proche quand vous \u00eates au loin\",\"datePublished\":\"2016-02-22T16:17:41+00:00\",\"dateModified\":\"2023-04-13T21:01:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/rester-proche-quand-vous-etes-au-loin\"},\"wordCount\":395,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/rester-proche-quand-vous-etes-au-loin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Untitled-design1-300x300.png\",\"keywords\":[\"conseils\",\"gardienne\",\"loin\",\"nounou\",\"proche\",\"voyage sans enfants\"],\"articleSection\":[\"Nanny\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/rester-proche-quand-vous-etes-au-loin#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/rester-proche-quand-vous-etes-au-loin\",\"url\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/rester-proche-quand-vous-etes-au-loin\",\"name\":\"Rester proche quand vous \u00eates au loin - SOSgarde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/rester-proche-quand-vous-etes-au-loin#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/rester-proche-quand-vous-etes-au-loin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Untitled-design1-300x300.png\",\"datePublished\":\"2016-02-22T16:17:41+00:00\",\"dateModified\":\"2023-04-13T21:01:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#\\\/schema\\\/person\\\/049d0f324600c83487a66abc831867fc\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/rester-proche-quand-vous-etes-au-loin\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/rester-proche-quand-vous-etes-au-loin#primaryimage\",\"url\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Untitled-design1-300x300.png\",\"contentUrl\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/Untitled-design1-300x300.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#website\",\"url\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/\",\"name\":\"SOSgarde\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#\\\/schema\\\/person\\\/049d0f324600c83487a66abc831867fc\",\"name\":\"Sosgarde\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g\",\"caption\":\"Sosgarde\"},\"url\":\"#\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rester proche quand vous \u00eates au loin - SOSgarde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin","og_locale":"fr_CA","og_type":"article","og_title":"Rester proche quand vous \u00eates au loin - SOSgarde","og_description":"Reading Time: 2 minutes Heureusement, je ne voyage plus autant pour le travail que je ne le faisais mais il y avait un temps o\u00f9 je prenais trois ou quatre vols par semaine. J\u2019avais l&#8217;habitude de dire que, pour moi, prendre un avion \u00e9tait comme prendre un bus. Voyager peut \u00eatre excitant, mais quand vous avez des enfants, cela [&hellip;]","og_url":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin","og_site_name":"SOSgarde","article_published_time":"2016-02-22T16:17:41+00:00","article_modified_time":"2023-04-13T21:01:18+00:00","og_image":[{"url":"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2016\/02\/Untitled-design1-300x300.png","type":"","width":"","height":""}],"author":"Sosgarde","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sosgarde","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin#article","isPartOf":{"@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin"},"author":{"name":"Sosgarde","@id":"https:\/\/wp.sosgarde.ca\/blogue\/#\/schema\/person\/049d0f324600c83487a66abc831867fc"},"headline":"Rester proche quand vous \u00eates au loin","datePublished":"2016-02-22T16:17:41+00:00","dateModified":"2023-04-13T21:01:18+00:00","mainEntityOfPage":{"@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin"},"wordCount":395,"commentCount":0,"image":{"@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin#primaryimage"},"thumbnailUrl":"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2016\/02\/Untitled-design1-300x300.png","keywords":["conseils","gardienne","loin","nounou","proche","voyage sans enfants"],"articleSection":["Nanny"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin","url":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin","name":"Rester proche quand vous \u00eates au loin - SOSgarde","isPartOf":{"@id":"https:\/\/wp.sosgarde.ca\/blogue\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin#primaryimage"},"image":{"@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin#primaryimage"},"thumbnailUrl":"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2016\/02\/Untitled-design1-300x300.png","datePublished":"2016-02-22T16:17:41+00:00","dateModified":"2023-04-13T21:01:18+00:00","author":{"@id":"https:\/\/wp.sosgarde.ca\/blogue\/#\/schema\/person\/049d0f324600c83487a66abc831867fc"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/rester-proche-quand-vous-etes-au-loin#primaryimage","url":"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2016\/02\/Untitled-design1-300x300.png","contentUrl":"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2016\/02\/Untitled-design1-300x300.png"},{"@type":"WebSite","@id":"https:\/\/wp.sosgarde.ca\/blogue\/#website","url":"https:\/\/wp.sosgarde.ca\/blogue\/","name":"SOSgarde","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.sosgarde.ca\/blogue\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/wp.sosgarde.ca\/blogue\/#\/schema\/person\/049d0f324600c83487a66abc831867fc","name":"Sosgarde","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g","caption":"Sosgarde"},"url":"#"}]}},"_links":{"self":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts\/1441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/comments?post=1441"}],"version-history":[{"count":1,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts\/1441\/revisions"}],"predecessor-version":[{"id":2512,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts\/1441\/revisions\/2512"}],"wp:attachment":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/media?parent=1441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/categories?post=1441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/tags?post=1441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}