{"id":537,"date":"2012-07-23T15:50:49","date_gmt":"2012-07-23T15:50:49","guid":{"rendered":"https:\/\/sosgarde.ca\/blogue\/?p=537"},"modified":"2023-04-13T20:55:38","modified_gmt":"2023-04-13T20:55:38","slug":"des-gateries-de-maman-cool","status":"publish","type":"post","link":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool","title":{"rendered":"Des G\u00e2teries de \u00ab Maman Cool \u00bb"},"content":{"rendered":"<span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\">3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p><em>Un billet de Marie-Christine Godbout de <a href=\"http:\/\/www.wooloo.ca\/\">www.wooloo.ca<\/a>.<\/em><\/p>\n<p>Lorsque qu\u2019on m&#8217;a demand\u00e9 d&#8217;\u00e9crire un billet pour <a href=\"https:\/\/sosgarde.ca\">SOSgarde<\/a>, je n&#8217;ai pas h\u00e9sit\u00e9 tr\u00e8s longtemps parce que bien que je sois tr\u00e8s occup\u00e9e, j&#8217;aime bien me donner des raisons de faire plaisir \u00e0 mes enfants et j&#8217;adore \u00e9crire! Le soir m\u00eame, j&#8217;ai trouv\u00e9 un sujet qui j&#8217;esp\u00e8re vous rappellera de bons souvenirs!<\/p>\n<p>Pour c\u00e9l\u00e9brer la victoire de nos petits U7 au soccer, nous sommes all\u00e9s \u00e0 la cr\u00e8me glac\u00e9e! Je n&#8217;ai pas jou\u00e9 au soccer tr\u00e8s longtemps, mais gr\u00e2ce \u00e0 ma s\u0153ur qui est une vraie championne de soccer, je n&#8217;ai que de bons souvenirs de nos nombreuses sorties \u00e0 la cantine apr\u00e8s ses parties de soccer. Je prenais toujours une molle au chocolat tremp\u00e9e dans le chocolat. Mais cette semaine, ce n&#8217;est pas une cr\u00e8me glac\u00e9e que j\u2019ai command\u00e9, c\u2019est un Mont Blanc (une slush avec de la cr\u00e8me glac\u00e9e aussi appel\u00e9 Barbotines ou Flotteur). Je pense bien que \u00e7a faisait 30 ans que je n&#8217;en avais pas mang\u00e9! \u00a0Je me suis ensuite mise \u00e0 penser \u00e0 ce qui me faisait vraiment plaisir de manger quand j&#8217;\u00e9tais petite. C\u2019est vraiment tr\u00e8s dr\u00f4le parce qu\u2019il y a seulement 3 choses tr\u00e8s tr\u00e8s pr\u00e9cises qui me sont venues en t\u00eate\u00a0:<\/p>\n<ol>\n<li>Les Ritz aux guimauves de Murielle, la m\u00e8re de mon amie Marisol;<\/li>\n<li>Les barbotines Coke-Cr\u00e8me glac\u00e9e vanille de Francine, la m\u00e8re de mon amie Marie-Jos\u00e9e;<\/li>\n<li>Les \u00ab\u00a0drinks\u00a0\u00bb 7Up-Grenadine de ma Grand-maman Yvonne.<\/li>\n<\/ol>\n<p>Je me rappelle tr\u00e8s bien que longtemps avant que j&#8217;aie des enfants, je me disais souvent que je serais une maman vraiment tr\u00e8s cool parce que j&#8217;aillais leur servir ces trois grandes recettes (duos serait plus appropri\u00e9)! Finalement, mis \u00e0 part le \u00ab drink\u00a0\u00bb 7Up-Grenadine qui est devenu un must \u00e0 tous nos partys, les deux autres \u00e9taient un peu tomb\u00e9s aux oubliettes. Et bien cette semaine, je suis devenue la maman cool que j&#8217;aspirais \u00e0 \u00eatre; je leur ai pr\u00e9par\u00e9 mes meilleurs souvenirs d&#8217;enfance en rafale! Je vous pr\u00e9viens, l&#8217;ingr\u00e9dient le plus sant\u00e9 de toutes ces g\u00e2teries est le bonheur! Les voici donc en images\u00a0:<\/p>\n<p><strong>Flotteurs Coke-Cr\u00e8me glac\u00e9e \u00e0 la vanille<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185748\/flotteur-coke-creme.png\"><img decoding=\"async\" class=\"size-medium wp-image-542 aligncenter\" src=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185748\/flotteur-coke-creme-300x101.png\" alt=\"\" width=\"300\" height=\"101\" srcset=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185748\/flotteur-coke-creme-300x101.png 300w, https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185748\/flotteur-coke-creme.png 630w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/strong><\/p>\n<p><strong>Ritz et guimauves<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185751\/riz-et-guimauve.png\"><img decoding=\"async\" class=\"size-medium wp-image-543 aligncenter\" src=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185751\/riz-et-guimauve-300x130.png\" alt=\"\" width=\"300\" height=\"130\" srcset=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185751\/riz-et-guimauve-300x130.png 300w, https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185751\/riz-et-guimauve.png 622w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/strong><\/p>\n<p><strong>7Up et grenadine<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185753\/7up-et-grenadine.png\"><img decoding=\"async\" class=\"size-medium wp-image-544 aligncenter\" src=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185753\/7up-et-grenadine-300x170.png\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185753\/7up-et-grenadine-300x170.png 300w, https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2012\/07\/06185753\/7up-et-grenadine.png 620w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/strong><\/p>\n<p>Les r\u00e9sultats? Je doute que dans 30 ans, une de ces trois recettes fasse partie de leur palmar\u00e8s de souvenirs gastronomiques et j&#8217;ai l&#8217;impression que mon statut de maman \u00ab\u00a0cool\u00a0\u00bb n&#8217;a gagn\u00e9 aucun point.\u00a0 Ils ont aim\u00e9, bien s\u00fbr parce que c&#8217;\u00e9tait quand m\u00eame bon, mais ils n&#8217;avaient d\u00e9finitivement pas mon emballement! Pas grave, j&#8217;ai pass\u00e9 une belle semaine \u00e0 me rappeler ces bons souvenirs, \u00e0 en parler avec des amies et \u00e0 enfin les partager avec mes enfants.<\/p>\n<p>On dit qu&#8217;il y a des gens qui passent dans nos vies et d&#8217;autres qui les marquent. Je pense que c&#8217;est la m\u00eame chose pour la nourriture. Et vous, est-ce qu&#8217;il y a des petites g\u00e2teries qui ont marqu\u00e9 votre jeunesse?\u00a0\u00a0 Qu&#8217;est-ce qui vous faisait vraiment plaisir de manger quand vous \u00e9tiez jeunes?<\/p>\n<p>Ce soir \u00e0 la maison, l&#8217;ami dun mes gar\u00e7ons soupait avec nous.\u00a0 Apr\u00e8s un weekend de tournoi de soccer, j&#8217;avais le go\u00fbt de relaxer, mais en pensant \u00e0 ce billet, j&#8217;ai plut\u00f4t d\u00e9cid\u00e9 de prendre 10 minutes pour faire des biscuits bananes-chocolats et g\u00e2ter notre invit\u00e9. Il en a mang\u00e9 six et m&#8217;a dit presque autant de fois qu&#8217;ils \u00e9taient vraiment bons! J&#8217;aimerais tellement que dans 30 ans il se rappelle de moi et mes biscuits de ce soir (hahaha!!)<\/p>\n<p>En attendant, il me fera plaisir de vous recevoir sur ma page facebook pour partager avec vous toutes sortes de bonnes id\u00e9es qui feront plaisir \u00e0 vos enfants <a href=\"http:\/\/www.facebook.com\/wooloo.ca\">www.facebook.com\/wooloo.ca<\/a>. Au plaisir de vous croiser!<\/p>\n<p><em><a href=\"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2012\/07\/Marie-Christine.jpg\"><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-552\" src=\"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2012\/07\/Marie-Christine-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Auteur\u00a0: Marie-Christine Godbout, maman de 5 enfants de 6 mois \u00e0 7 ans et fondatrice du site <a href=\"http:\/\/www.wooloo.ca\/\">www.wooloo.ca<\/a> qui est en ligne depuis 3 mois d\u00e9j\u00e0! Il s&#8217;agit d&#8217;un site d\u00e9di\u00e9 aux f\u00eates d&#8217;enfants. Sur son blogue (www.wooloo.ca\/blog), vous y trouverez toutes sortes d&#8217;id\u00e9es pour faire plaisir aux enfants; des activit\u00e9s, des recettes, des id\u00e9es cadeaux, des id\u00e9es de sortie.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\">3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span> Un billet de Marie-Christine Godbout de www.wooloo.ca.<\/p>\n<p>Lorsque qu\u2019on m&#8217;a demand\u00e9 d&#8217;\u00e9crire un billet pour SOSgarde, je n&#8217;ai pas h\u00e9sit\u00e9 tr\u00e8s longtemps parce que bien que je sois tr\u00e8s occup\u00e9e, j&#8217;aime bien me donner des raisons de faire plaisir \u00e0 mes enfants et j&#8217;adore \u00e9crire! Le soir m\u00eame, j&#8217;ai trouv\u00e9 un sujet qui j&#8217;esp\u00e8re vous rappellera de bons souvenirs!<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[547],"tags":[25,5,6,31],"class_list":["post-537","post","type-post","status-publish","format-standard","hentry","category-nanny","tag-enfant","tag-famille","tag-maman","tag-preparation"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Des G\u00e2teries de \u00ab Maman Cool \u00bb - SOSgarde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des G\u00e2teries de \u00ab Maman Cool \u00bb - SOSgarde\" \/>\n<meta property=\"og:description\" content=\"Reading Time: 3 minutes Un billet de Marie-Christine Godbout de www.wooloo.ca. Lorsque qu\u2019on m&#039;a demand\u00e9 d&#039;\u00e9crire un billet pour SOSgarde, je n&#039;ai pas h\u00e9sit\u00e9 tr\u00e8s longtemps parce que bien que je sois tr\u00e8s occup\u00e9e, j&#039;aime bien me donner des raisons de faire plaisir \u00e0 mes enfants et j&#039;adore \u00e9crire! Le soir m\u00eame, j&#039;ai trouv\u00e9 un sujet qui j&#039;esp\u00e8re vous rappellera de bons souvenirs!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool\" \/>\n<meta property=\"og:site_name\" content=\"SOSgarde\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-23T15:50:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-13T20:55:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2012\/07\/flotteur-coke-creme-300x101.png\" \/>\n<meta name=\"author\" content=\"Sosgarde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sosgarde\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/des-gateries-de-maman-cool#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/des-gateries-de-maman-cool\"},\"author\":{\"name\":\"Sosgarde\",\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#\\\/schema\\\/person\\\/049d0f324600c83487a66abc831867fc\"},\"headline\":\"Des G\u00e2teries de \u00ab Maman Cool \u00bb\",\"datePublished\":\"2012-07-23T15:50:49+00:00\",\"dateModified\":\"2023-04-13T20:55:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/des-gateries-de-maman-cool\"},\"wordCount\":756,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/des-gateries-de-maman-cool#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/flotteur-coke-creme-300x101.png\",\"keywords\":[\"enfant\",\"famille\",\"maman\",\"pr\u00e9paration\"],\"articleSection\":[\"Nanny\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/des-gateries-de-maman-cool#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/des-gateries-de-maman-cool\",\"url\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/des-gateries-de-maman-cool\",\"name\":\"Des G\u00e2teries de \u00ab Maman Cool \u00bb - SOSgarde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/des-gateries-de-maman-cool#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/des-gateries-de-maman-cool#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/flotteur-coke-creme-300x101.png\",\"datePublished\":\"2012-07-23T15:50:49+00:00\",\"dateModified\":\"2023-04-13T20:55:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#\\\/schema\\\/person\\\/049d0f324600c83487a66abc831867fc\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/des-gateries-de-maman-cool\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/nanny\\\/des-gateries-de-maman-cool#primaryimage\",\"url\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/flotteur-coke-creme-300x101.png\",\"contentUrl\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/flotteur-coke-creme-300x101.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#website\",\"url\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/\",\"name\":\"SOSgarde\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#\\\/schema\\\/person\\\/049d0f324600c83487a66abc831867fc\",\"name\":\"Sosgarde\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g\",\"caption\":\"Sosgarde\"},\"url\":\"#\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Des G\u00e2teries de \u00ab Maman Cool \u00bb - SOSgarde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool","og_locale":"fr_CA","og_type":"article","og_title":"Des G\u00e2teries de \u00ab Maman Cool \u00bb - SOSgarde","og_description":"Reading Time: 3 minutes Un billet de Marie-Christine Godbout de www.wooloo.ca. Lorsque qu\u2019on m'a demand\u00e9 d'\u00e9crire un billet pour SOSgarde, je n'ai pas h\u00e9sit\u00e9 tr\u00e8s longtemps parce que bien que je sois tr\u00e8s occup\u00e9e, j'aime bien me donner des raisons de faire plaisir \u00e0 mes enfants et j'adore \u00e9crire! Le soir m\u00eame, j'ai trouv\u00e9 un sujet qui j'esp\u00e8re vous rappellera de bons souvenirs!","og_url":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool","og_site_name":"SOSgarde","article_published_time":"2012-07-23T15:50:49+00:00","article_modified_time":"2023-04-13T20:55:38+00:00","og_image":[{"url":"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2012\/07\/flotteur-coke-creme-300x101.png","type":"","width":"","height":""}],"author":"Sosgarde","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sosgarde","Estimation du temps de lecture":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool#article","isPartOf":{"@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool"},"author":{"name":"Sosgarde","@id":"https:\/\/wp.sosgarde.ca\/blogue\/#\/schema\/person\/049d0f324600c83487a66abc831867fc"},"headline":"Des G\u00e2teries de \u00ab Maman Cool \u00bb","datePublished":"2012-07-23T15:50:49+00:00","dateModified":"2023-04-13T20:55:38+00:00","mainEntityOfPage":{"@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool"},"wordCount":756,"commentCount":0,"image":{"@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool#primaryimage"},"thumbnailUrl":"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2012\/07\/flotteur-coke-creme-300x101.png","keywords":["enfant","famille","maman","pr\u00e9paration"],"articleSection":["Nanny"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool","url":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool","name":"Des G\u00e2teries de \u00ab Maman Cool \u00bb - SOSgarde","isPartOf":{"@id":"https:\/\/wp.sosgarde.ca\/blogue\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool#primaryimage"},"image":{"@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool#primaryimage"},"thumbnailUrl":"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2012\/07\/flotteur-coke-creme-300x101.png","datePublished":"2012-07-23T15:50:49+00:00","dateModified":"2023-04-13T20:55:38+00:00","author":{"@id":"https:\/\/wp.sosgarde.ca\/blogue\/#\/schema\/person\/049d0f324600c83487a66abc831867fc"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/sosgarde.ca\/blogue\/nanny\/des-gateries-de-maman-cool#primaryimage","url":"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2012\/07\/flotteur-coke-creme-300x101.png","contentUrl":"https:\/\/sosgarde.ca\/blogue\/wp-content\/uploads\/2012\/07\/flotteur-coke-creme-300x101.png"},{"@type":"WebSite","@id":"https:\/\/wp.sosgarde.ca\/blogue\/#website","url":"https:\/\/wp.sosgarde.ca\/blogue\/","name":"SOSgarde","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.sosgarde.ca\/blogue\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/wp.sosgarde.ca\/blogue\/#\/schema\/person\/049d0f324600c83487a66abc831867fc","name":"Sosgarde","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g","caption":"Sosgarde"},"url":"#"}]}},"_links":{"self":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts\/537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/comments?post=537"}],"version-history":[{"count":1,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts\/537\/revisions"}],"predecessor-version":[{"id":2660,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts\/537\/revisions\/2660"}],"wp:attachment":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/media?parent=537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/categories?post=537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/tags?post=537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}