{"id":826,"date":"2013-08-16T12:09:20","date_gmt":"2013-08-16T12:09:20","guid":{"rendered":"https:\/\/sosgarde.ca\/blogue\/?p=826"},"modified":"2024-12-13T23:42:40","modified_gmt":"2024-12-13T23:42:40","slug":"concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t","status":"publish","type":"post","link":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t","title":{"rendered":"Concours pour la Rentr\u00e9e &#8211; Gagnez des \u00e9tiquettes d&#8217;identifications Identi-T"},"content":{"rendered":"<span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\">&lt; 1<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><h1>Concours pour la Rentr\u00e9e &#8211; Gagnez des \u00e9tiquettes d&#8217;identifications Identi-T<\/h1>\n<p>Ah la Rentr\u00e9e&#8230; On l&#8217;aime pour ne plus se casser la t\u00eate qu&#8217;est ce que on fait avec les enfants, mais on sait bien qu&#8217;il y aura pleins \u00e0 faire. Incluant pr\u00e9parer les affaires de nos enfants pour l&#8217;\u00e9cole. Pourquoi ne pas vous aider avec les \u00e9tiquettes d&#8217;identifications de <a href=\"http:\/\/www.identi-t.com\/index.php\" target=\"_blank\" rel=\"noopener\">Identi-T<\/a>? On a 3 ensembles de Grande Ecole Identi-T\u00a0d&#8217;une valeur de 45,95$ \u00e0 faire tirer et qui incluent 48 \u00e9tiquettes mini-languettes, 48 \u00e9tiquettes languettes, 12 \u00e9tiquettes souliers (pour 6 paires), 3 identifications bagage.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2013\/08\/06185917\/image_ecole_Identi-T.jpg\"><img decoding=\"async\" class=\"aligncenter size-thumbnail wp-image-827\" title=\"Etiquettes d'identification ecole_Identi-T\" src=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2013\/08\/06185917\/image_ecole_Identi-T-150x150.jpg\" alt=\"\" width=\"200\" height=\"200\" srcset=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2013\/08\/06185917\/image_ecole_Identi-T-150x150.jpg 150w, https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2013\/08\/06185917\/image_ecole_Identi-T-300x300.jpg 300w, https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2013\/08\/06185917\/image_ecole_Identi-T.jpg 450w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<p>Identi-T est une<a href=\"https:\/\/www.lesaffaires.com\/outils\/classements\/le-classement-2024-des-300-plus-grandes-entreprises-du-quebec-2\/\"> entreprise qu\u00e9b\u00e9coise<\/a> qui a vu le jour en 2005. Identi-T offre toute une gamme de produits d&#8217;identifications, tous aussi int\u00e9ressants les uns que les autres. Nos autocollants personnalis\u00e9s d&#8217;ic\u00f4nes et de couleurs sont devenus indispensables pour tous les membres de la maison. Avec leur possibilit\u00e9 de tout identifier, ils s&#8217;occupent des effets des enfants rentrant \u00e0 l&#8217;\u00e9cole ou encore des personnes \u00e2g\u00e9es dans les maisons de retraite en un tour de main.<\/p>\n<p>Pour gagner un des 3 ensembles Grande \u00c9cole il y a plusieurs fa\u00e7ons de participer. Plus de fa\u00e7ons vous participez, plus vous avez des chances \u00e0 gagner!<\/p>\n<p>Engagez le <a href=\"https:\/\/wp.sosgarde.ca\/candidats\/gardienne-enfants\/Laval?lat=45.56172&amp;lon=-73.74613\">babysitter<\/a> id\u00e9ale pour vos enfants pendant cette rentr\u00e9e scolaire, centaines de <a href=\"https:\/\/wp.sosgarde.ca\/candidats\/aide-aines\/Montr%C3%A9al?lat=45.50283&amp;lon=-73.5728\">soins \u00e0 domicile<\/a> sur <a href=\"https:\/\/wp.sosgarde.ca\/blogue\/\">SOS garde<\/a> .<\/p>\n<p>&nbsp;<\/p>\n<p><a id=\"rc-f61a3d8\" class=\"rafl\" href=\"http:\/\/www.rafflecopter.com\/rafl\/display\/f61a3d8\/\" rel=\"nofollow\">a Rafflecopter giveaway<\/a><br \/>\n<script src=\"\/\/d12vno17mo87cx.cloudfront.net\/embed\/rafl\/cptr.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Reading Time: <\/span> <span class=\"rt-time\">&lt; 1<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span> Concours Rentr\u00e9e 2013 SOSgarde: 3 ensembles Grande Ecole d&#8217;\u00e9tiquettes d&#8217;identification de Identi-T \u00e0 gagner. <\/p>\n","protected":false},"author":7,"featured_media":3644,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[4,549],"tags":[411,136],"class_list":["post-826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baby-sitter","category-sosgarde","tag-concours","tag-rentree"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Concours pour la Rentr\u00e9e - Gagnez des \u00e9tiquettes d&#039;identifications Identi-T - SOSgarde<\/title>\n<meta name=\"description\" content=\"Participez \u00e0 notre concours de rentr\u00e9e scolaire et tentez de gagner 3 ensembles de Grande Ecole Identi-T d&#039;une valeur de 45,95$, comprenant des \u00e9tiquettes d&#039;identification pour les affaires de vos enfants. Ne vous cassez plus la t\u00eate et pr\u00e9parez la rentr\u00e9e en toute simplicit\u00e9 avec Identi-T.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Concours pour la Rentr\u00e9e - Gagnez des \u00e9tiquettes d&#039;identifications Identi-T - SOSgarde\" \/>\n<meta property=\"og:description\" content=\"Participez \u00e0 notre concours de rentr\u00e9e scolaire et tentez de gagner 3 ensembles de Grande Ecole Identi-T d&#039;une valeur de 45,95$, comprenant des \u00e9tiquettes d&#039;identification pour les affaires de vos enfants. Ne vous cassez plus la t\u00eate et pr\u00e9parez la rentr\u00e9e en toute simplicit\u00e9 avec Identi-T.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t\" \/>\n<meta property=\"og:site_name\" content=\"SOSgarde\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-16T12:09:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-13T23:42:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2024\/04\/22220820\/books-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sosgarde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sosgarde\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/sosgarde\\\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/sosgarde\\\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t\"},\"author\":{\"name\":\"Sosgarde\",\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#\\\/schema\\\/person\\\/049d0f324600c83487a66abc831867fc\"},\"headline\":\"Concours pour la Rentr\u00e9e &#8211; Gagnez des \u00e9tiquettes d&#8217;identifications Identi-T\",\"datePublished\":\"2013-08-16T12:09:20+00:00\",\"dateModified\":\"2024-12-13T23:42:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/sosgarde\\\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t\"},\"wordCount\":241,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/sosgarde\\\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sosgarde.nyc3.digitaloceanspaces.com\\\/Prod\\\/blogue\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/22220820\\\/books-2-scaled.jpg\",\"keywords\":[\"Concours\",\"rentr\u00e9e\"],\"articleSection\":[\"Babysitter\",\"SOSgarde\"],\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/sosgarde\\\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/sosgarde\\\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t\",\"url\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/sosgarde\\\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t\",\"name\":\"Concours pour la Rentr\u00e9e - Gagnez des \u00e9tiquettes d'identifications Identi-T - SOSgarde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/sosgarde\\\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/sosgarde\\\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sosgarde.nyc3.digitaloceanspaces.com\\\/Prod\\\/blogue\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/22220820\\\/books-2-scaled.jpg\",\"datePublished\":\"2013-08-16T12:09:20+00:00\",\"dateModified\":\"2024-12-13T23:42:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#\\\/schema\\\/person\\\/049d0f324600c83487a66abc831867fc\"},\"description\":\"Participez \u00e0 notre concours de rentr\u00e9e scolaire et tentez de gagner 3 ensembles de Grande Ecole Identi-T d'une valeur de 45,95$, comprenant des \u00e9tiquettes d'identification pour les affaires de vos enfants. Ne vous cassez plus la t\u00eate et pr\u00e9parez la rentr\u00e9e en toute simplicit\u00e9 avec Identi-T.\",\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/sosgarde\\\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/sosgarde.ca\\\/blogue\\\/sosgarde\\\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#primaryimage\",\"url\":\"https:\\\/\\\/sosgarde.nyc3.digitaloceanspaces.com\\\/Prod\\\/blogue\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/22220820\\\/books-2-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/sosgarde.nyc3.digitaloceanspaces.com\\\/Prod\\\/blogue\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/22220820\\\/books-2-scaled.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"Journ\u00e9e Mondiale du livre et du droit d'auteur.\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#website\",\"url\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/\",\"name\":\"SOSgarde\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wp.sosgarde.ca\\\/blogue\\\/#\\\/schema\\\/person\\\/049d0f324600c83487a66abc831867fc\",\"name\":\"Sosgarde\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g\",\"caption\":\"Sosgarde\"},\"url\":\"#\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Concours pour la Rentr\u00e9e - Gagnez des \u00e9tiquettes d'identifications Identi-T - SOSgarde","description":"Participez \u00e0 notre concours de rentr\u00e9e scolaire et tentez de gagner 3 ensembles de Grande Ecole Identi-T d'une valeur de 45,95$, comprenant des \u00e9tiquettes d'identification pour les affaires de vos enfants. Ne vous cassez plus la t\u00eate et pr\u00e9parez la rentr\u00e9e en toute simplicit\u00e9 avec Identi-T.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t","og_locale":"fr_CA","og_type":"article","og_title":"Concours pour la Rentr\u00e9e - Gagnez des \u00e9tiquettes d'identifications Identi-T - SOSgarde","og_description":"Participez \u00e0 notre concours de rentr\u00e9e scolaire et tentez de gagner 3 ensembles de Grande Ecole Identi-T d'une valeur de 45,95$, comprenant des \u00e9tiquettes d'identification pour les affaires de vos enfants. Ne vous cassez plus la t\u00eate et pr\u00e9parez la rentr\u00e9e en toute simplicit\u00e9 avec Identi-T.","og_url":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t","og_site_name":"SOSgarde","article_published_time":"2013-08-16T12:09:20+00:00","article_modified_time":"2024-12-13T23:42:40+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2024\/04\/22220820\/books-2-scaled.jpg","type":"image\/jpeg"}],"author":"Sosgarde","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sosgarde","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#article","isPartOf":{"@id":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t"},"author":{"name":"Sosgarde","@id":"https:\/\/wp.sosgarde.ca\/blogue\/#\/schema\/person\/049d0f324600c83487a66abc831867fc"},"headline":"Concours pour la Rentr\u00e9e &#8211; Gagnez des \u00e9tiquettes d&#8217;identifications Identi-T","datePublished":"2013-08-16T12:09:20+00:00","dateModified":"2024-12-13T23:42:40+00:00","mainEntityOfPage":{"@id":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t"},"wordCount":241,"commentCount":0,"image":{"@id":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#primaryimage"},"thumbnailUrl":"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2024\/04\/22220820\/books-2-scaled.jpg","keywords":["Concours","rentr\u00e9e"],"articleSection":["Babysitter","SOSgarde"],"inLanguage":"fr-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t","url":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t","name":"Concours pour la Rentr\u00e9e - Gagnez des \u00e9tiquettes d'identifications Identi-T - SOSgarde","isPartOf":{"@id":"https:\/\/wp.sosgarde.ca\/blogue\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#primaryimage"},"image":{"@id":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#primaryimage"},"thumbnailUrl":"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2024\/04\/22220820\/books-2-scaled.jpg","datePublished":"2013-08-16T12:09:20+00:00","dateModified":"2024-12-13T23:42:40+00:00","author":{"@id":"https:\/\/wp.sosgarde.ca\/blogue\/#\/schema\/person\/049d0f324600c83487a66abc831867fc"},"description":"Participez \u00e0 notre concours de rentr\u00e9e scolaire et tentez de gagner 3 ensembles de Grande Ecole Identi-T d'une valeur de 45,95$, comprenant des \u00e9tiquettes d'identification pour les affaires de vos enfants. Ne vous cassez plus la t\u00eate et pr\u00e9parez la rentr\u00e9e en toute simplicit\u00e9 avec Identi-T.","inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/sosgarde.ca\/blogue\/sosgarde\/concours-pour-la-rentree-gagnez-des-etiquettes-didentifications-identi-t#primaryimage","url":"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2024\/04\/22220820\/books-2-scaled.jpg","contentUrl":"https:\/\/sosgarde.nyc3.digitaloceanspaces.com\/Prod\/blogue\/wp-content\/uploads\/2024\/04\/22220820\/books-2-scaled.jpg","width":1707,"height":2560,"caption":"Journ\u00e9e Mondiale du livre et du droit d'auteur."},{"@type":"WebSite","@id":"https:\/\/wp.sosgarde.ca\/blogue\/#website","url":"https:\/\/wp.sosgarde.ca\/blogue\/","name":"SOSgarde","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.sosgarde.ca\/blogue\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/wp.sosgarde.ca\/blogue\/#\/schema\/person\/049d0f324600c83487a66abc831867fc","name":"Sosgarde","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a51bc3a0a7941101d785cc5f9d635a390c6f0f75d31bca81d55ded045a01b448?s=96&d=mm&r=g","caption":"Sosgarde"},"url":"#"}]}},"_links":{"self":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts\/826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/comments?post=826"}],"version-history":[{"count":3,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts\/826\/revisions"}],"predecessor-version":[{"id":3893,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/posts\/826\/revisions\/3893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/media\/3644"}],"wp:attachment":[{"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/media?parent=826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/categories?post=826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosgarde.ca\/blogue\/wp-json\/wp\/v2\/tags?post=826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}